{"id":1184,"date":"2025-09-22T21:22:07","date_gmt":"2025-09-22T21:22:07","guid":{"rendered":"https:\/\/ohiounity.org\/?page_id=1184"},"modified":"2025-10-01T13:10:20","modified_gmt":"2025-10-01T13:10:20","slug":"in-the-community","status":"publish","type":"page","link":"https:\/\/ohiounity.org\/index.php\/in-the-community\/","title":{"rendered":"In the Community"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1184\" class=\"elementor elementor-1184\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eefd53a e-con-full e-flex e-con e-parent\" data-id=\"eefd53a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-54e0c6d e-con-full e-flex e-con e-child\" data-id=\"54e0c6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d19eeb5 e-con-full e-flex e-con e-child\" data-id=\"d19eeb5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-98bc263 e-con-full e-flex e-con e-child\" data-id=\"98bc263\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16b116b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"16b116b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">IN THE COMMUNITY <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f99e02e elementor-widget elementor-widget-text-editor\" data-id=\"f99e02e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>VIEW HOW WE ARE MAKING CHANGE AND IMPACTING THE COMMUNITY.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a0bef8 e-flex e-con-boxed e-con e-parent\" data-id=\"1a0bef8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b17bdaa elementor-widget elementor-widget-text-editor\" data-id=\"b17bdaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"133\" data-end=\"586\">At Ohio Unity, our strength comes from the people we serve and stand beside. Our&nbsp;<strong data-start=\"214\" data-end=\"234\">In the Community<\/strong> gallery highlights our work across Ohio\u2014bringing neighbors together, advocating for change, and building a stronger future through civic engagement. From rallies and educational workshops to voter outreach and community celebrations, these moments reflect the power of unity in action. Explore the gallery to see how we\u2019re making an impact together.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6aa6f6 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"f6aa6f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7fa337c e-flex e-con-boxed e-con e-child\" data-id=\"7fa337c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-297b250 e-con-full e-flex e-con e-child\" data-id=\"297b250\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1df776 elementor-widget elementor-widget-image\" data-id=\"b1df776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-225x300.jpg\" class=\"attachment-medium size-medium wp-image-1056\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-500x667.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85b2149 e-con-full e-flex e-con e-child\" data-id=\"85b2149\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8de1d elementor-widget elementor-widget-image\" data-id=\"1e8de1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Ohio-protesting-225x300.jpg\" class=\"attachment-medium size-medium wp-image-1198\" alt=\"Ohio Redistricting Protest\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Ohio-protesting-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Ohio-protesting.jpg 240w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-475291f e-con-full e-flex e-con e-child\" data-id=\"475291f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beebbbe elementor-widget elementor-widget-image\" data-id=\"beebbbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-285x300.jpg\" class=\"attachment-medium size-medium wp-image-1054\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-285x300.jpg 285w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-700x736.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-500x526.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531.jpg 720w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07937e6 e-flex e-con-boxed e-con e-child\" data-id=\"07937e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a3bf2b1 e-con-full e-flex e-con e-child\" data-id=\"a3bf2b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0420754 elementor-widget elementor-widget-image\" data-id=\"0420754\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-225x300.jpg\" class=\"attachment-medium size-medium wp-image-1039\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-500x667.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0942a35 e-con-full e-flex e-con e-child\" data-id=\"0942a35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d7f3a elementor-widget elementor-widget-image\" data-id=\"d9d7f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-240x300.jpg\" class=\"attachment-medium size-medium wp-image-1030\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-500x625.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024.jpg 768w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4df0693 e-con-full e-flex e-con e-child\" data-id=\"4df0693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72064bc elementor-widget elementor-widget-image\" data-id=\"72064bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-300x225.jpg\" class=\"attachment-medium size-medium wp-image-1021\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-800x600.jpg 800w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8012075 e-con-full e-flex e-con e-child\" data-id=\"8012075\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c32cac3 e-con-full e-flex e-con e-child\" data-id=\"c32cac3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3960f2f elementor-widget elementor-widget-image\" data-id=\"3960f2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-225x300.jpg\" class=\"attachment-medium size-medium wp-image-1043\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-500x667.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429.jpg 1536w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afa242a e-con-full e-flex e-con e-child\" data-id=\"afa242a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33932f4 elementor-widget elementor-widget-image\" data-id=\"33932f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-225x300.jpg\" class=\"attachment-medium size-medium wp-image-1058\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-500x667.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447.jpg 720w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbfe4e4 e-con-full e-flex e-con e-child\" data-id=\"bbfe4e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bad0126 elementor-widget elementor-widget-image\" data-id=\"bad0126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"300\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-214x300.jpg\" class=\"attachment-medium size-medium wp-image-1007\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-214x300.jpg 214w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-500x700.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788.jpg 638w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f53da4 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"6f53da4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f05808 elementor-widget elementor-widget-fast-gallery-mosaic\" data-id=\"7f05808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fast-gallery-mosaic.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<br><style type='text\/css'>\r\n\t\t\t\t.FGM-Collage .fg-gallery-item .gallery-icon {\r\n\t\t\t\t\topacity:0;\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1 {\r\n\t\t\t\t\tmargin: auto;\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.FGM-Collage .fg-gallery-item {\r\n\t\t\t\t\ttext-align: center;\t\t\t\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1 .fg-gallery-caption {\r\n\t\t\t\t\tmargin-left: 0;\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic .fg-gallery-caption, \r\n\t\t\t\t#gallery-1.fastgallery_mosaic .fg-gallery-caption:hover {\r\n\t\t\t\t\tbackground-color:rgba( 252 , 97 , 93 , 1);\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery .gallery-icon .fg_zoom a, \r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FC615D;\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style1 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style2 .gallery-icon .fg_zoom a {\r\n\t\t\t\t\tbackground:rgba( 255 , 255 , 255 , 0.3);\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style2 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style3 .fg_zoom, #gallery-1.fastgallery_mosaic.gallery.fg_style3 .fg_zoom:hover {\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style3 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\t\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style4 .fg-gallery-caption,\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style4 .gallery-icon .fg_zoom a, \r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style4 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style4 .gallery-icon .fg_zoom a, \r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style4 .gallery-icon .fg_zoom a:hover\t{\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\r\n\t\t\t\t}\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style5 .gallery-icon .fg_zoom a, \r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style5 .gallery-icon .fg_zoom a:hover\t{\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground-color:rgba( 252 , 97 , 93 , 1);\r\n\t\t\t\t}\t\t\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style6 .gallery-icon .fg_zoom a,\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style6 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\t\t\t\t\r\n\t\t\t\t}\r\n\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style6 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style7 .gallery-icon .fg_zoom a,\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style7 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\t\t\t\t\r\n\t\t\t\t}\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style7 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\r\n\t\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style8 .gallery-icon .fg_zoom a,\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style8 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\t\t\t\t\r\n\t\t\t\t}\r\n\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style8 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\r\n\t\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style9 .gallery-icon .fg_zoom a,\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style9 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\t\t\t\t\r\n\t\t\t\t}\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style9 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}\r\n\t\t\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style10 .gallery-icon .fg_zoom a,\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style10 .gallery-icon .fg_zoom a:hover {\r\n\t\t\t\t\tcolor:#FFFFFF;\r\n\t\t\t\t\tbackground:rgba( 252 , 97 , 93 , 1);\t\t\t\t\r\n\t\t\t\t}\t\t\r\n\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style10 .fg-gallery-caption {\r\n\t\t\t\t\tcolor:#FFFFFF;\t\r\n\t\t\t\t}#gallery-1.fastgallery_mosaic.gallery span {\r\n\t\t\t\t\t\t\t\t\t\tfont-size:20px!important;\r\n\t\t\t\t\t}\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.gallery .gallery-icon .fg-zoom-icon {\r\n\t\t\t\t\t\t\t\t\t\tmargin-left:-10px!important;\r\n\t\t\t\t\t\t\t\t\t\tmargin-top:-40px;\r\n\t\t\t\t\t}\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style2 .gallery-icon .fg-zoom-icon,\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.gallery.fg_style5 .gallery-icon .fg-zoom-icon  {\r\n\t\t\t\t\t\t\t\t\t\tmargin-top:-10px;\r\n\t\t\t\t\t}\t\t\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.gallery .gallery-icon.no-caption .fg-zoom-icon {\r\n\t\t\t\t\t\t\t\t\t\tmargin-top:-10px!important;\r\n\t\t\t\t\t}\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style7 .fg-gallery-caption,\r\n\t\t\t\t\t#gallery-1.fastgallery_mosaic.fg_style8 .fg-gallery-caption {\r\n\t\t\t\t\t\t\t\t\t\ttop:55%;\r\n\t\t\t\t\t}\r\n\t\t\t\t\t<\/style>\n\t\t<script type=\"text\/javascript\">jQuery(function($){$(window).load(function () {function collage() {\r\n\t\t\t\t\t\t\t\t\t\t$('#gallery-1.FGM-Collage').removeWhitespace().collagePlus(\r\n\t\t\t\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t\t\t\t\t\t'targetHeight'  \t\t: 300,\r\n\t\t\t\t\t\t\t\t\t\t\t\t'padding'\t\t\t\t: 5,\r\n\t\t\t\t\t\t\t\t\t\t\t\t'allowPartialLastRow'   : true\r\n\t\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t);\r\n\t\t\t\t\t\t\t\t\t};\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t\t\t\t\t\tcollage();\r\n\t\t\t\t\t\t\t\t\t\t$('.FGM-Collage .fg-gallery-item .gallery-icon').css(\"opacity\", 1);\r\n\t\t\t\t\t\t\t\t\t});\t\r\n\t\t\t\t\t\t\t\t\tvar resizeTimer = null;\r\n\t\t\t\t\t\t\t\t\tvar windowSize = $(window).width();\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t$(window).bind('resize', function() {\r\n\t\t\t\t\t\t\t\t\t\t$('.FGM-Collage .fg-gallery-item').css(\"opacity\", 0);\r\n\t\t\t\t\t\t\t\t\t\tif($(window).width() != windowSize){\r\n\t\t\t\t\t\t\t\t\t\t\t\tif (windowSize < 1160 ) {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\tvar size = 250;\r\n\t\t\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\telse {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\tvar size = 300;\r\n\t\t\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\/\/console.log(size);\r\n\r\n\t\t\t\t\t\t\t\t\t\tif (resizeTimer) clearTimeout(resizeTimer);\r\n\t\t\t\t\t\t\t\t\t\tresizeTimer = setTimeout(collage(size), 250);\r\n\t\t\t\t\t\t\t\t\t\twindowSize = $(window).width();\r\n\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t});\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t});\r\n\t\t\t\t\t});<\/script><script type=\"text\/javascript\">\r\n\t\t\t\t\t\tjQuery(function($){\r\n\t\t\t\t\t\t\t$('#gallery-1 .fg_magnificPopup').magnificPopup({\r\n\t\t\t\t\t\t\t\ttype: 'image',\t\t\t\t\t\r\n\t\t\t\t\t\t\t\tgallery:{\r\n\t\t\t\t\t\t\t\t\tenabled:true\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t});\r\n\t\t\t\t\t\t});\t\t\r\n\t\t\t\t\t<\/script>\n\t\t<div id='gallery-1' class='FGM-Collage gallery galleryid-1 gallery-size-fg_layout3 fastgallery_mosaic fpg fg_responsive fg_style2 fg_over_image_on fg_layout3'><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"731\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"in the community\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-295x300.jpg 295w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-700x711.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-500x508.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"731\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"in the community\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-295x300.jpg 295w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-700x711.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154603308_7374234885273613231-e1758163824267-500x508.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154630207_7374234998097856739-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154552403_7374234671764390353-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154526665_7374234563811950919-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"348\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865-300x163.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865-500x272.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"348\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865-300x163.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154870834_7374236007362671865-500x272.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-1024x768.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-1536x1152.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-800x600.jpg 800w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-1024x768.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-1536x1152.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154952974_7374236351880585721-800x600.jpg 800w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154992762_7374236518765328892-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155028400_7374236668240603867-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155069502_7374236840636581933-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155184588_7374237323340990271-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935.jpg 540w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935-169x300.jpg 169w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935-500x889.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935-540x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935.jpg 540w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935-169x300.jpg 169w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154735944_7374235441590196935-500x889.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154236175_7374233345406713447-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154344312_7374233798966432820-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154361212_7374233869852290145-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154392302_7374234000250220652-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"757\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-285x300.jpg 285w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-700x736.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-500x526.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"757\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-285x300.jpg 285w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-700x736.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154415390_7374234097088271759-e1758223074531-500x526.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154488094_7374234402032454927-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154816040_7374235777537498429-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1462\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648.jpg 1462w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-214x300.jpg 214w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-731x1024.jpg 731w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-768x1076.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-1097x1536.jpg 1097w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-700x981.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-500x700.jpg 500w\" sizes=\"(max-width: 1462px) 100vw, 1462px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1462\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648.jpg 1462w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-214x300.jpg 214w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-731x1024.jpg 731w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-768x1076.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-1097x1536.jpg 1097w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-700x981.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154779402_7374235623865429648-500x700.jpg 500w\" sizes=\"(max-width: 1462px) 100vw, 1462px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"Ohio Felons Voting Rights\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"Ohio Felons Voting Rights\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758154760048_7374235542692112668-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-300x169.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-1024x576.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-768x432.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-1536x864.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-700x394.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-500x281.jpg 500w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-300x169.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-1024x576.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-768x432.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-1536x864.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-700x394.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155708868_7374239522330908405-500x281.jpg 500w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"707\" height=\"622\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417.jpg 707w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-300x264.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-700x616.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-500x440.jpg 500w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-708x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"707\" height=\"622\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417.jpg 707w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-300x264.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-700x616.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155819874_7374239987921027047-e1758810061417-500x440.jpg 500w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155850432_7374240116093891228-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155878656_7374240234471622204-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"Ohio Unity Coalition\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"Ohio Unity Coalition\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155903810_7374240339976249602-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-768x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155644059_7374239250501349643-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-768x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155676935_7374239388399386854-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-768x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-240x300.jpg 240w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-700x875.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155625379_7374239172151028024-500x625.jpg 500w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"News for Ohio Voters\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"News for Ohio Voters\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155588872_7374239019030726432-1-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155921381_7374240413675606471-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334.jpg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155941435_7374240497788421334-800x600.jpg 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238.jpg 1080w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-300x300.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-1024x1024.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-150x150.jpg 150w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-768x768.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-700x700.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-800x800.jpg 800w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-500x500.jpg 500w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238.jpg 1080w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-300x300.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-1024x1024.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-150x150.jpg 150w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-768x768.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-700x700.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-800x800.jpg 800w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758155989100_7374240697706356238-500x500.jpg 500w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156010605_7374240787906880603-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156035196_7374240891047080693-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156049930_7374240952845714729-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"2016\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958.jpg 976w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-145x300.jpg 145w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-496x1024.jpg 496w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-768x1586.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-744x1536.jpg 744w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-700x1446.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-500x1033.jpg 500w\" sizes=\"(max-width: 976px) 100vw, 976px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-976x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"976\" height=\"2016\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958.jpg 976w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-145x300.jpg 145w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-496x1024.jpg 496w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-768x1586.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-744x1536.jpg 744w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-700x1446.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156063021_7374241007753851958-500x1033.jpg 500w\" sizes=\"(max-width: 976px) 100vw, 976px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"2016\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989.jpg 980w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-768x1580.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-747x1536.jpg 747w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-700x1440.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-500x1029.jpg 500w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-980x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"2016\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989.jpg 980w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-768x1580.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-747x1536.jpg 747w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-700x1440.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156081671_7374241085980991989-500x1029.jpg 500w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156160002_7374241414523237547-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"Donate image\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736.jpg 920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-288x300.jpg 288w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-768x801.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-700x730.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-500x522.jpg 500w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-920x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"Donate image\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736.jpg 920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-288x300.jpg 288w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-768x801.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-700x730.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156315857_7374242068224877736-500x522.jpg 500w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"893\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788.jpg 638w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-214x300.jpg 214w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-500x700.jpg 500w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-638x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"893\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788.jpg 638w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-214x300.jpg 214w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156330678_7374242130388539096-e1759324175788-500x700.jpg 500w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-300x200.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-768x512.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-700x466.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-500x333.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-1000x682.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-300x200.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-768x512.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-700x466.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156280705_7374241920787677529-500x333.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"1316\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-500x1028.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-640x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"1316\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156259267_7374241830871922261-500x1028.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"1316\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-500x1028.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-640x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"1316\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480.jpg 640w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-146x300.jpg 146w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-498x1024.jpg 498w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156231755_7374241715476263480-500x1028.jpg 500w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086.jpg 480w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156188994_7374241536123449086-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-720x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690.jpg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690.jpg 720w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/facebook_1758156173525_7374241471244696690-500x667.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n.jpg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-225x300.jpg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-768x1024.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-1152x1536.jpg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-700x933.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/485895357_695339586331277_8735706865464382694_n-500x667.jpg 500w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-1024x768.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-1536x1152.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-800x600.jpg 800w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-1000x800.jpg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n.jpg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n.jpg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-300x225.jpg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-1024x768.jpg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-768x576.jpg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-1536x1152.jpg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-700x525.jpg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-500x375.jpg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/480042276_666780752520494_3653267258921616603_n-800x600.jpg 800w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170127_161626-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-scaled.jpeg 2560w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-1024x768.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-1536x1152.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-2048x1536.jpeg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-800x600.jpeg 800w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-scaled.jpeg 2560w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-1024x768.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-1536x1152.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-2048x1536.jpeg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170303_112256-800x600.jpeg 800w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20170422_150408-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567.jpeg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-300x169.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-768x432.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-700x394.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-500x281.jpeg 500w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567.jpeg 960w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-300x169.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-768x432.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-700x394.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/IMG_3567-500x281.jpeg 500w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1852\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-300x289.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-1024x988.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-768x741.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-1536x1482.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-700x675.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-500x482.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1852\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-300x289.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-1024x988.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-768x741.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-1536x1482.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-700x675.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240917_122859-scaled-e1758162241753-500x482.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"Get Involved with OUC\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"Get Involved with OUC\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240913_183305-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20241031_170500-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"756\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319.jpeg 1008w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-800x600.jpeg 800w\" sizes=\"(max-width: 1008px) 100vw, 1008px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-1000x756.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"756\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319.jpeg 1008w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/Resized_IMG4387247483114551549_9770757572319-800x600.jpeg 800w\" sizes=\"(max-width: 1008px) 100vw, 1008px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-scaled.jpeg\" class=\"attachment-fgm-3-6 size-fgm-3-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240910_210505-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115226-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon landscape no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-scaled.jpeg 2560w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-1024x768.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-1536x1152.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-2048x1536.jpeg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-800x600.jpeg 800w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-scaled.jpeg\" class=\"attachment-fgm-1-6 size-fgm-1-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-scaled.jpeg 2560w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-300x225.jpeg 300w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-1024x768.jpeg 1024w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-768x576.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-1536x1152.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-2048x1536.jpeg 2048w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-700x525.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-500x375.jpeg 500w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240701_115332-800x600.jpeg 800w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/20240614_142856-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div><div class='fg-gallery-item  '><div class='gallery-icon portrait no-caption'><div class='fg_zoom'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><a href='https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-1000x800.jpeg' title=\"\" data-rel-fg='prettyPhoto[album-1]' class='fg_magnificPopup'><span class='fg-zoom-icon icon-plus'><\/span><span style='display:none'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-scaled.jpeg\" class=\"attachment-fgm-2-6 size-fgm-2-6\" alt=\"\" srcset=\"https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-scaled.jpeg 1920w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-225x300.jpeg 225w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-768x1024.jpeg 768w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-1152x1536.jpeg 1152w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-1536x2048.jpeg 1536w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-700x933.jpeg 700w, https:\/\/ohiounity.org\/wp-content\/uploads\/2025\/09\/1000009389-500x667.jpeg 500w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/a><\/div><\/div><\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a80a50 e-flex e-con-boxed e-con e-parent\" data-id=\"8a80a50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>IN THE COMMUNITY VIEW HOW WE ARE MAKING CHANGE AND IMPACTING THE COMMUNITY.\u00a0 At Ohio Unity, our strength comes from the people we serve and stand beside. Our&nbsp;In the Community gallery highlights our work across Ohio\u2014bringing neighbors together, advocating for change, and building a stronger future through civic engagement. From rallies and educational workshops to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1184","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/pages\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":20,"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/pages\/1184\/revisions"}],"predecessor-version":[{"id":1339,"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/pages\/1184\/revisions\/1339"}],"wp:attachment":[{"href":"https:\/\/ohiounity.org\/index.php\/wp-json\/wp\/v2\/media?parent=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}